{"id":92,"date":"2026-07-13T17:31:02","date_gmt":"2026-07-13T22:31:02","guid":{"rendered":"https:\/\/www.festiq.one\/?page_id=92"},"modified":"2026-08-03T16:12:42","modified_gmt":"2026-08-03T21:12:42","slug":"atracciones","status":"publish","type":"page","link":"https:\/\/www.festiq.one\/index.php\/atracciones\/","title":{"rendered":"Atracciones"},"content":{"rendered":"<ul>\n<li>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/accommodations-category-norway-intro.jpg\" alt=\"\"><\/p>\n<h2>Isla Kong<\/h2>\n<p>Piscina<\/p>\n<p><a href=\"#\">Ver m\u00e1s<\/a><\/p>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/accommodations-category-germany-intro.jpg\" alt=\"\"><\/p>\n<h2>Piscina 2<\/h2>\n<p>Piscina<\/p>\n<p><a href=\"#\">Ver m\u00e1s<\/a><\/p>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/accommodations-category-great-britain-intro.jpg\" alt=\"\"><\/p>\n<h2>Piscina 1<\/h2>\n<p>Piscina<\/p>\n<p><a href=\"#\">Ver m\u00e1s<\/a><\/p>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/accommodations-category-spain-intro.jpg\" alt=\"\"><\/p>\n<h2>Piscina de Chorros<\/h2>\n<p>Piscina<\/p>\n<p><a href=\"#\">Ver m\u00e1s<\/a><\/p>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/accommodations-category-croatia-intro.jpg\" alt=\"\"><\/p>\n<h2>Piscina 3<\/h2>\n<p>Piscina<\/p>\n<div>Coming soon!<\/div>\n<p><a href=\"#\">Ver m\u00e1s<\/a><\/p>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/accommodations-category-portugal-intro.jpg\" alt=\"\"><\/p>\n<h2>Tobog\u00e1n Racer<\/h2>\n<p>Tobog\u00e1n<\/p>\n<div>Coming soon!<\/div>\n<p><a href=\"#\">Ver m\u00e1s<\/a><\/p>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/accommodations-category-norway-intro.jpg\" alt=\"\"><\/p>\n<h2>Bosque Perdido de los Dinosaurios<\/h2>\n<p>Atracci\u00f3n<\/p>\n<p><a href=\"#\">Ver m\u00e1s<\/a><\/p>\n<\/li>\n<\/ul>\n<h2>Find Your Home<br class=\"uk-visible@m\"> Away From Home<\/h2>\n<div>\n<p>Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo irure dolor in reprehenderit in voluptate velit esse cillum dolore eu fugiat nulla pariatur. Excepteur sint occaecat cupidatat non proident, sunt in culpa qui officia deserunt mollit anim id est laborum.<\/p>\n<\/div>\n<div>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/accommodations-tag-exclusive-architecture-intro.jpg\" alt=\"\"><\/p>\n<h3>Exclusive Architecture<\/h3>\n<p><a href=\"#\">View Houses<\/a><\/p>\n<\/div>\n<ul>\n<li>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/accommodations-tag-exclusive-architecture-intro.jpg\" alt=\"\"><\/p>\n<h3>Exclusive Architecture<\/h3>\n<p><a href=\"#\">View Houses<\/a><\/p>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/accommodations-tag-family-vacation-intro.jpg\" alt=\"\"><\/p>\n<h3>Family Vacation<\/h3>\n<p><a href=\"#\">View Houses<\/a><\/p>\n<\/li>\n<\/ul>\n<div>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/accommodations-tag-family-vacation-intro.jpg\" alt=\"\"><\/p>\n<h3>Family Vacation<\/h3>\n<p><a href=\"#\">View Houses<\/a><\/p>\n<\/div>\n<ul>\n<li>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/accommodations-tag-with-a-pool-intro.jpg\" alt=\"\"><\/p>\n<h3>With a Pool<\/h3>\n<p><a href=\"#\">View Houses<\/a><\/p>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/accommodations-tag-near-the-beach-intro.jpg\" alt=\"\"><\/p>\n<h3>Near the Beach<\/h3>\n<p><a href=\"#\">View Houses<\/a><\/p>\n<\/li>\n<\/ul>\n<div>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/accommodations-tag-winter-escapes-intro.jpg\" alt=\"\"><\/p>\n<h3>Winter Escapes<\/h3>\n<p><a href=\"#\">View Houses<\/a><\/p>\n<\/div>\n<ul>\n<li>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/accommodations-tag-winter-escapes-intro.jpg\" alt=\"\"><\/p>\n<h3>Winter Escapes<\/h3>\n<p><a href=\"#\">View Houses<\/a><\/p>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/accommodations-tag-in-the-mountains-intro.jpg\" alt=\"\"><\/p>\n<h3>In the Mountains<\/h3>\n<p><a href=\"#\">View Houses<\/a><\/p>\n<\/li>\n<\/ul>\n<ul>\n<li>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/accommodations-tag-cozy-places-intro.jpg\" alt=\"\"><\/p>\n<h3>Cozy Places<\/h3>\n<p><a href=\"#\">View Houses<\/a><\/p>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/accommodations-tag-tiny-homes-intro.jpg\" alt=\"\"><\/p>\n<h3>Tiny Homes<\/h3>\n<p><a href=\"#\">View Houses<\/a><\/p>\n<\/li>\n<\/ul>\n<div>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/accommodations-tag-in-the-mountains-intro.jpg\" alt=\"\"><\/p>\n<h3>In the Mountains<\/h3>\n<p><a href=\"#\">View Houses<\/a><\/p>\n<\/div>\n<div>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/accommodations-tag-urban-chic-intro.jpg\" alt=\"\"><\/p>\n<h3>Urban Chic<\/h3>\n<p><a href=\"#\">View Houses<\/a><\/p>\n<\/div>\n<div>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/accommodations-tag-urban-chic-intro.jpg\" alt=\"\"><\/p>\n<h3>Urban Chic<\/h3>\n<p><a href=\"#\">View Houses<\/a><\/p>\n<\/div>\n<ul>\n<li>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/accommodations-tag-pets-welcome-intro.jpg\" alt=\"\"><\/p>\n<h3>Pets Welcome<\/h3>\n<p><a href=\"#\">View Houses<\/a><\/p>\n<\/li>\n<li>\n<p>        <img decoding=\"async\" src=\"\/wp-content\/uploads\/accommodations-tag-in-the-woods-intro.jpg\" alt=\"\"><\/p>\n<h3>In the Woods<\/h3>\n<p><a href=\"#\">View Houses<\/a><\/p>\n<\/li>\n<\/ul>\n<div>Ask Design Escapes<\/div>\n<h2>Need Help Making a Decision?<\/h2>\n<div>Lorem ipsum dolor sit amet, consectetur adipis cing elit, sed do eiusmod tempor incididunt.<\/div>\n<p><p>\n        <a href=\"mailto:info@example.com\">Contact Us<\/a>\n    <\/p>\n<\/p>\n<p><!--more--><br \/>\n<!-- {\"type\":\"layout\",\"children\":[{\"type\":\"section\",\"props\":{\"animation_delay\":false,\"image_position\":\"center-center\",\"padding_bottom\":\"none\",\"padding_top\":\"none\",\"style\":\"default\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"\",\"width\":\"\"},\"children\":[{\"type\":\"row\",\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\"},\"children\":[{\"type\":\"overlay-slider\",\"props\":{\"content_margin\":\"remove\",\"css\":\".el-item {\\n    text-shadow: 2px 2px 3px #000;\\n}\",\"image_height\":\"600\",\"image_loading\":true,\"image_transition\":\"scale-down\",\"link_style\":\"primary\",\"link_text\":\"Ver m\u00e1s\",\"margin_bottom\":\"default\",\"margin_top\":\"default\",\"meta_align\":\"above-title\",\"meta_element\":\"div\",\"meta_style\":\"h6\",\"nav\":\"\",\"nav_align\":\"center\",\"nav_below\":true,\"nav_breakpoint\":\"s\",\"nav_position\":\"bottom-center\",\"nav_position_margin\":\"medium\",\"overlay_link\":true,\"overlay_mode\":\"cover\",\"overlay_padding\":\"large\",\"overlay_position\":\"top-center\",\"overlay_transition\":\"fade\",\"overlay_transition_background\":false,\"show_content\":true,\"show_hover_image\":true,\"show_hover_video\":true,\"show_link\":true,\"show_meta\":true,\"show_title\":true,\"slidenav\":\"default\",\"slidenav_breakpoint\":\"s\",\"slidenav_hover\":true,\"slidenav_margin\":\"medium\",\"slidenav_outside_breakpoint\":\"xl\",\"slider_autoplay\":true,\"slider_autoplay_interval\":\"3\",\"slider_autoplay_pause\":true,\"slider_center\":true,\"slider_gap\":\"small\",\"slider_width\":\"fixed\",\"slider_width_default\":\"1-2\",\"slider_width_medium\":\"1-5\",\"slider_width_small\":\"1-3\",\"text_align\":\"center\",\"text_color\":\"light\",\"text_color_hover\":false,\"title_element\":\"h2\",\"title_hover_style\":\"reset\",\"title_margin\":\"small\",\"title_margin_auto\":true},\"children\":[{\"type\":\"overlay-slider_item\",\"props\":{\"image\":\"wp-content\/uploads\/accommodations-category-norway-intro.jpg\",\"link\":\"#\",\"meta\":\"Piscina\",\"text_color\":\"light\",\"title\":\"Isla Kong\"}},{\"type\":\"overlay-slider_item\",\"props\":{\"image\":\"wp-content\/uploads\/accommodations-category-germany-intro.jpg\",\"link\":\"#\",\"meta\":\"Piscina\",\"text_color\":\"light\",\"title\":\"Piscina 2\"}},{\"type\":\"overlay-slider_item\",\"props\":{\"image\":\"wp-content\/uploads\/accommodations-category-great-britain-intro.jpg\",\"link\":\"#\",\"meta\":\"Piscina\",\"text_color\":\"light\",\"title\":\"Piscina 1\"}},{\"type\":\"overlay-slider_item\",\"props\":{\"image\":\"wp-content\/uploads\/accommodations-category-spain-intro.jpg\",\"link\":\"#\",\"meta\":\"Piscina\",\"text_color\":\"light\",\"title\":\"Piscina de Chorros\"}},{\"type\":\"overlay-slider_item\",\"props\":{\"content\":\"Coming soon!\",\"image\":\"wp-content\/uploads\/accommodations-category-croatia-intro.jpg\",\"link\":\"#\",\"meta\":\"Piscina\",\"text_color\":\"light\",\"title\":\"Piscina 3\"}},{\"type\":\"overlay-slider_item\",\"props\":{\"content\":\"Coming soon!\",\"image\":\"wp-content\/uploads\/accommodations-category-portugal-intro.jpg\",\"link\":\"#\",\"meta\":\"Tobog\u00e1n\",\"text_color\":\"light\",\"title\":\"Tobog\u00e1n Racer\"}},{\"type\":\"overlay-slider_item\",\"props\":{\"image\":\"wp-content\/uploads\/accommodations-category-norway-intro.jpg\",\"link\":\"#\",\"meta\":\"Atracci\u00f3n\",\"text_color\":\"light\",\"title\":\"Bosque Perdido de los Dinosaurios\"}}]}]}]}],\"name\":\"Categories\"},{\"type\":\"section\",\"props\":{\"image_position\":\"center-center\",\"padding_bottom\":\"large\",\"padding_top\":\"large\",\"style\":\"default\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"\",\"width\":\"large\"},\"children\":[{\"type\":\"row\",\"props\":{\"layout\":\"1-3,2-3\"},\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"1-3\"},\"children\":[{\"type\":\"headline\",\"props\":{\"content\":\"Find Your Home<br class=\\\"uk-visible@m\\\"> Away From Home\",\"image_align\":\"left\",\"image_margin\":\"xsmall\",\"title_element\":\"h2\"}}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"2-3\"},\"children\":[{\"type\":\"text\",\"props\":{\"column\":\"1-2\",\"column_breakpoint\":\"m\",\"content\":\"\n\n<p>Lorem ipsum dolor sit amet, consectetur adipiscing elit, sed do eiusmod tempor incididunt ut labore et dolore magna aliqua. Ut enim ad minim veniam, quis nostrud exercitation ullamco laboris nisi ut aliquip ex ea commodo irure dolor in reprehenderit in voluptate velit esse cillum dolore eu fugiat nulla pariatur. Excepteur sint occaecat cupidatat non proident, sunt in culpa qui officia deserunt mollit anim id est laborum.<\/p>\n\n\",\"margin_bottom\":\"default\",\"margin_top\":\"default\"}}]}]}],\"name\":\"About\"},{\"type\":\"section\",\"props\":{\"animation_delay\":false,\"image_position\":\"bottom-left\",\"image_size\":\"contain\",\"padding_bottom\":\"none\",\"padding_top\":\"none\",\"style\":\"default\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"\",\"width\":\"large\"},\"children\":[{\"type\":\"row\",\"props\":{\"column_gap\":\"small\",\"layout\":\"1-2,1-2\",\"row_gap\":\"collapse\"},\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"1-2\"},\"children\":[{\"type\":\"overlay\",\"props\":{\"content\":\"\",\"content_margin\":\"small\",\"image\":\"wp-content\/uploads\/accommodations-tag-exclusive-architecture-intro.jpg\",\"image_height\":\"900\",\"image_transition\":\"scale-down\",\"image_width\":\"900\",\"link\":\"#\",\"link_margin\":\"remove\",\"link_style\":\"\",\"link_text\":\"View Houses\",\"margin_bottom\":\"remove\",\"margin_top\":\"default\",\"meta_align\":\"below-title\",\"meta_element\":\"div\",\"meta_style\":\"text-meta\",\"overlay_hover\":false,\"overlay_link\":true,\"overlay_mode\":\"cover\",\"overlay_position\":\"bottom-left\",\"overlay_style\":\"\",\"overlay_transition\":\"fade\",\"text_align\":\"\",\"text_color\":\"light\",\"title\":\"Exclusive Architecture\",\"title_element\":\"h3\",\"title_hover_style\":\"reset\",\"visibility\":\"m\"},\"modified\":\"2020-11-24T16:30:51.601Z\"},{\"type\":\"gallery\",\"props\":{\"filter_align\":\"left\",\"filter_all\":true,\"filter_grid_breakpoint\":\"m\",\"filter_grid_width\":\"auto\",\"filter_position\":\"top\",\"filter_style\":\"tab\",\"grid_column_gap\":\"small\",\"grid_default\":\"1\",\"grid_medium\":\"\",\"grid_row_gap\":\"small\",\"grid_small\":\"2\",\"image_height\":\"610\",\"image_transition\":\"scale-down\",\"image_width\":\"610\",\"item_animation\":true,\"lightbox_bg_close\":true,\"link_margin\":\"remove\",\"link_style\":\"\",\"link_text\":\"View Houses\",\"margin_bottom\":\"\",\"margin_top\":\"\",\"meta_align\":\"below-title\",\"meta_element\":\"div\",\"meta_style\":\"text-meta\",\"overlay_hover\":false,\"overlay_link\":true,\"overlay_mode\":\"cover\",\"overlay_position\":\"bottom-left\",\"overlay_style\":\"\",\"overlay_transition\":\"fade\",\"parallax_easing\":\"1\",\"show_content\":true,\"show_hover_image\":true,\"show_hover_video\":true,\"show_link\":true,\"show_meta\":true,\"show_title\":true,\"text_align\":\"\",\"text_color\":\"light\",\"title_element\":\"h3\",\"title_hover_style\":\"reset\",\"visibility\":\"hidden-m\"},\"children\":[{\"type\":\"gallery_item\",\"props\":{\"image\":\"wp-content\/uploads\/accommodations-tag-exclusive-architecture-intro.jpg\",\"link\":\"#\",\"title\":\"Exclusive Architecture\"}},{\"type\":\"gallery_item\",\"props\":{\"image\":\"wp-content\/uploads\/accommodations-tag-family-vacation-intro.jpg\",\"link\":\"#\",\"title\":\"Family Vacation\"}}]}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"1-2\"},\"children\":[{\"type\":\"overlay\",\"props\":{\"content\":\"\",\"content_margin\":\"small\",\"image\":\"wp-content\/uploads\/accommodations-tag-family-vacation-intro.jpg\",\"image_height\":\"440\",\"image_transition\":\"scale-down\",\"image_width\":\"900\",\"link\":\"#\",\"link_margin\":\"remove\",\"link_style\":\"\",\"link_text\":\"View Houses\",\"margin_bottom\":\"remove\",\"margin_top\":\"default\",\"meta_align\":\"below-title\",\"meta_element\":\"div\",\"meta_style\":\"text-meta\",\"overlay_hover\":false,\"overlay_link\":true,\"overlay_mode\":\"cover\",\"overlay_position\":\"bottom-left\",\"overlay_style\":\"\",\"overlay_transition\":\"fade\",\"text_align\":\"\",\"text_color\":\"light\",\"title\":\"Family Vacation\",\"title_element\":\"h3\",\"title_hover_style\":\"reset\",\"visibility\":\"m\"},\"modified\":\"2020-11-24T16:30:51.601Z\"},{\"type\":\"gallery\",\"props\":{\"class\":\"uk-grid-margin-small\",\"filter_align\":\"left\",\"filter_all\":true,\"filter_grid_breakpoint\":\"m\",\"filter_grid_width\":\"auto\",\"filter_position\":\"top\",\"filter_style\":\"tab\",\"grid_column_gap\":\"small\",\"grid_default\":\"1\",\"grid_medium\":\"\",\"grid_row_gap\":\"small\",\"grid_small\":\"2\",\"image_height\":\"610\",\"image_transition\":\"scale-down\",\"image_width\":\"610\",\"item_animation\":true,\"lightbox_bg_close\":true,\"link_margin\":\"remove\",\"link_style\":\"\",\"link_text\":\"View Houses\",\"margin_bottom\":\"\",\"margin_top\":\"\",\"meta_align\":\"below-title\",\"meta_element\":\"div\",\"meta_style\":\"text-meta\",\"overlay_hover\":false,\"overlay_link\":true,\"overlay_mode\":\"cover\",\"overlay_position\":\"bottom-left\",\"overlay_style\":\"\",\"overlay_transition\":\"fade\",\"parallax_easing\":\"1\",\"show_content\":true,\"show_hover_image\":true,\"show_hover_video\":true,\"show_link\":true,\"show_meta\":true,\"show_title\":true,\"text_align\":\"\",\"text_color\":\"light\",\"title_element\":\"h3\",\"title_hover_style\":\"reset\"},\"children\":[{\"type\":\"gallery_item\",\"props\":{\"image\":\"wp-content\/uploads\/accommodations-tag-with-a-pool-intro.jpg\",\"link\":\"#\",\"title\":\"With a Pool\"}},{\"type\":\"gallery_item\",\"props\":{\"image\":\"wp-content\/uploads\/accommodations-tag-near-the-beach-intro.jpg\",\"link\":\"#\",\"title\":\"Near the Beach\"}}]}]}]},{\"type\":\"row\",\"props\":{\"column_gap\":\"small\",\"layout\":\"1-2,1-2\",\"row_gap\":\"small\"},\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"1-2\"},\"children\":[{\"type\":\"overlay\",\"props\":{\"content\":\"\",\"content_margin\":\"small\",\"image\":\"wp-content\/uploads\/accommodations-tag-winter-escapes-intro.jpg\",\"image_height\":\"440\",\"image_transition\":\"scale-down\",\"image_width\":\"900\",\"link\":\"#\",\"link_margin\":\"remove\",\"link_style\":\"\",\"link_text\":\"View Houses\",\"margin_bottom\":\"remove\",\"margin_top\":\"default\",\"meta_align\":\"below-title\",\"meta_element\":\"div\",\"meta_style\":\"text-meta\",\"overlay_hover\":false,\"overlay_link\":true,\"overlay_mode\":\"cover\",\"overlay_position\":\"bottom-left\",\"overlay_style\":\"\",\"overlay_transition\":\"fade\",\"text_align\":\"\",\"text_color\":\"light\",\"title\":\"Winter Escapes\",\"title_element\":\"h3\",\"title_hover_style\":\"reset\",\"visibility\":\"m\"},\"modified\":\"2020-11-24T16:30:51.601Z\"},{\"type\":\"gallery\",\"props\":{\"filter_align\":\"left\",\"filter_all\":true,\"filter_grid_breakpoint\":\"m\",\"filter_grid_width\":\"auto\",\"filter_position\":\"top\",\"filter_style\":\"tab\",\"grid_column_gap\":\"small\",\"grid_default\":\"1\",\"grid_medium\":\"\",\"grid_row_gap\":\"small\",\"grid_small\":\"2\",\"image_height\":\"610\",\"image_transition\":\"scale-down\",\"image_width\":\"610\",\"item_animation\":true,\"lightbox_bg_close\":true,\"link_margin\":\"remove\",\"link_style\":\"\",\"link_text\":\"View Houses\",\"margin_bottom\":\"small\",\"margin_top\":\"remove\",\"meta_align\":\"below-title\",\"meta_element\":\"div\",\"meta_style\":\"text-meta\",\"overlay_hover\":false,\"overlay_link\":true,\"overlay_mode\":\"cover\",\"overlay_position\":\"bottom-left\",\"overlay_style\":\"\",\"overlay_transition\":\"fade\",\"parallax_easing\":\"1\",\"show_content\":true,\"show_hover_image\":true,\"show_hover_video\":true,\"show_link\":true,\"show_meta\":true,\"show_title\":true,\"text_align\":\"\",\"text_color\":\"light\",\"title_element\":\"h3\",\"title_hover_style\":\"reset\",\"visibility\":\"hidden-m\"},\"children\":[{\"type\":\"gallery_item\",\"props\":{\"image\":\"wp-content\/uploads\/accommodations-tag-winter-escapes-intro.jpg\",\"link\":\"#\",\"title\":\"Winter Escapes\"}},{\"type\":\"gallery_item\",\"props\":{\"image\":\"wp-content\/uploads\/accommodations-tag-in-the-mountains-intro.jpg\",\"link\":\"#\",\"title\":\"In the Mountains\"}}]},{\"type\":\"gallery\",\"props\":{\"class\":\"uk-grid-margin-small\",\"filter_align\":\"left\",\"filter_all\":true,\"filter_grid_breakpoint\":\"m\",\"filter_grid_width\":\"auto\",\"filter_position\":\"top\",\"filter_style\":\"tab\",\"grid_column_gap\":\"small\",\"grid_default\":\"1\",\"grid_medium\":\"\",\"grid_row_gap\":\"small\",\"grid_small\":\"2\",\"image_height\":\"610\",\"image_transition\":\"scale-down\",\"image_width\":\"610\",\"item_animation\":true,\"lightbox_bg_close\":true,\"link_margin\":\"remove\",\"link_style\":\"\",\"link_text\":\"View Houses\",\"margin_bottom\":\"\",\"margin_top\":\"\",\"meta_align\":\"below-title\",\"meta_element\":\"div\",\"meta_style\":\"text-meta\",\"overlay_hover\":false,\"overlay_link\":true,\"overlay_mode\":\"cover\",\"overlay_position\":\"bottom-left\",\"overlay_style\":\"\",\"overlay_transition\":\"fade\",\"parallax_easing\":\"1\",\"show_content\":true,\"show_hover_image\":true,\"show_hover_video\":true,\"show_link\":true,\"show_meta\":true,\"show_title\":true,\"text_align\":\"\",\"text_color\":\"light\",\"title_element\":\"h3\",\"title_hover_style\":\"reset\"},\"children\":[{\"type\":\"gallery_item\",\"props\":{\"image\":\"wp-content\/uploads\/accommodations-tag-cozy-places-intro.jpg\",\"link\":\"#\",\"title\":\"Cozy Places\"}},{\"type\":\"gallery_item\",\"props\":{\"image\":\"wp-content\/uploads\/accommodations-tag-tiny-homes-intro.jpg\",\"link\":\"#\",\"title\":\"Tiny Homes\"}}]}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"1-2\"},\"children\":[{\"type\":\"overlay\",\"props\":{\"content\":\"\",\"content_margin\":\"small\",\"image\":\"wp-content\/uploads\/accommodations-tag-in-the-mountains-intro.jpg\",\"image_height\":\"1800\",\"image_transition\":\"scale-down\",\"image_width\":\"1800\",\"link\":\"#\",\"link_margin\":\"remove\",\"link_style\":\"\",\"link_text\":\"View Houses\",\"margin_bottom\":\"remove\",\"margin_top\":\"default\",\"meta_align\":\"below-title\",\"meta_element\":\"div\",\"meta_style\":\"text-meta\",\"overlay_hover\":false,\"overlay_link\":true,\"overlay_mode\":\"cover\",\"overlay_position\":\"bottom-left\",\"overlay_style\":\"\",\"overlay_transition\":\"fade\",\"text_align\":\"\",\"text_color\":\"light\",\"title\":\"In the Mountains\",\"title_element\":\"h3\",\"title_hover_style\":\"reset\",\"visibility\":\"m\"},\"modified\":\"2020-11-24T16:30:51.601Z\"}]}]},{\"type\":\"row\",\"props\":{\"column_gap\":\"small\",\"layout\":\"1-2,1-2\",\"row_gap\":\"small\"},\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"1-2\"},\"children\":[{\"type\":\"overlay\",\"props\":{\"content\":\"\",\"content_margin\":\"small\",\"image\":\"wp-content\/uploads\/accommodations-tag-urban-chic-intro.jpg\",\"image_height\":\"440\",\"image_transition\":\"scale-down\",\"image_width\":\"900\",\"link\":\"#\",\"link_margin\":\"remove\",\"link_style\":\"\",\"link_text\":\"View Houses\",\"margin_bottom\":\"remove\",\"margin_top\":\"default\",\"meta_align\":\"below-title\",\"meta_element\":\"div\",\"meta_style\":\"text-meta\",\"overlay_hover\":false,\"overlay_link\":true,\"overlay_mode\":\"cover\",\"overlay_position\":\"bottom-left\",\"overlay_style\":\"\",\"overlay_transition\":\"fade\",\"text_align\":\"\",\"text_color\":\"light\",\"title\":\"Urban Chic\",\"title_element\":\"h3\",\"title_hover_style\":\"reset\",\"visibility\":\"s\"},\"modified\":\"2020-11-24T16:30:51.601Z\"},{\"type\":\"overlay\",\"props\":{\"content\":\"\",\"content_margin\":\"small\",\"image\":\"wp-content\/uploads\/accommodations-tag-urban-chic-intro.jpg\",\"image_height\":\"610\",\"image_transition\":\"scale-down\",\"image_width\":\"610\",\"link\":\"#\",\"link_margin\":\"remove\",\"link_style\":\"\",\"link_text\":\"View Houses\",\"margin_bottom\":\"default\",\"margin_top\":\"remove\",\"meta_align\":\"below-title\",\"meta_element\":\"div\",\"meta_style\":\"text-meta\",\"overlay_hover\":false,\"overlay_link\":true,\"overlay_mode\":\"cover\",\"overlay_position\":\"bottom-left\",\"overlay_style\":\"\",\"overlay_transition\":\"fade\",\"text_align\":\"\",\"text_color\":\"light\",\"title\":\"Urban Chic\",\"title_element\":\"h3\",\"title_hover_style\":\"reset\",\"visibility\":\"hidden-s\"},\"modified\":\"2020-11-24T16:30:51.601Z\"}]},{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"1-2\"},\"children\":[{\"type\":\"gallery\",\"props\":{\"filter_align\":\"left\",\"filter_all\":true,\"filter_grid_breakpoint\":\"m\",\"filter_grid_width\":\"auto\",\"filter_position\":\"top\",\"filter_style\":\"tab\",\"grid_column_gap\":\"small\",\"grid_default\":\"1\",\"grid_medium\":\"\",\"grid_row_gap\":\"small\",\"grid_small\":\"2\",\"image_height\":\"610\",\"image_transition\":\"scale-down\",\"image_width\":\"610\",\"item_animation\":true,\"lightbox_bg_close\":true,\"link_margin\":\"remove\",\"link_style\":\"\",\"link_text\":\"View Houses\",\"margin_bottom\":\"small\",\"margin_top\":\"small\",\"meta_align\":\"below-title\",\"meta_element\":\"div\",\"meta_style\":\"text-meta\",\"overlay_hover\":false,\"overlay_link\":true,\"overlay_mode\":\"cover\",\"overlay_position\":\"bottom-left\",\"overlay_style\":\"\",\"overlay_transition\":\"fade\",\"parallax_easing\":\"1\",\"show_content\":true,\"show_hover_image\":true,\"show_hover_video\":true,\"show_link\":true,\"show_meta\":true,\"show_title\":true,\"text_align\":\"\",\"text_color\":\"light\",\"title_element\":\"h3\",\"title_hover_style\":\"reset\"},\"children\":[{\"type\":\"gallery_item\",\"props\":{\"image\":\"wp-content\/uploads\/accommodations-tag-pets-welcome-intro.jpg\",\"link\":\"#\",\"title\":\"Pets Welcome\"}},{\"type\":\"gallery_item\",\"props\":{\"image\":\"wp-content\/uploads\/accommodations-tag-in-the-woods-intro.jpg\",\"link\":\"#\",\"title\":\"In the Woods\"}}]}]}]}],\"name\":\"Tags\"},{\"type\":\"section\",\"props\":{\"animation\":\"fade\",\"image\":\"wp-content\/uploads\/discover-cta-bg.jpg\",\"image_position\":\"bottom-left\",\"image_size\":\"contain\",\"image_width\":\"2560\",\"padding_bottom\":\"xlarge\",\"padding_top\":\"xlarge\",\"style\":\"default\",\"title_breakpoint\":\"xl\",\"title_position\":\"top-left\",\"title_rotation\":\"left\",\"vertical_align\":\"\",\"width\":\"default\"},\"children\":[{\"type\":\"row\",\"props\":{\"alignment\":\"right\",\"margin_bottom\":\"xlarge\",\"margin_top\":\"xlarge\"},\"children\":[{\"type\":\"column\",\"props\":{\"image_position\":\"center-center\",\"position_sticky_breakpoint\":\"m\",\"width_medium\":\"1-2\",\"width_small\":\"2-3\"},\"children\":[{\"type\":\"headline\",\"props\":{\"animation\":\"slide-top-small\",\"content\":\"Ask Design Escapes\",\"image_align\":\"left\",\"image_margin\":\"xsmall\",\"margin_top\":\"remove\",\"text_align\":\"left\",\"text_align_breakpoint\":\"s\",\"text_align_fallback\":\"center\",\"title_color\":\"primary\",\"title_element\":\"div\",\"title_style\":\"h6\"}},{\"type\":\"headline\",\"props\":{\"content\":\"Need Help Making a Decision?\",\"image_align\":\"left\",\"image_margin\":\"xsmall\",\"margin_top\":\"remove\",\"text_align\":\"left\",\"text_align_breakpoint\":\"s\",\"text_align_fallback\":\"center\",\"title_element\":\"h2\"}},{\"type\":\"text\",\"props\":{\"column_breakpoint\":\"m\",\"content\":\"Lorem ipsum dolor sit amet, consectetur adipis cing elit, sed do eiusmod tempor incididunt.\",\"margin_bottom\":\"default\",\"margin_top\":\"default\",\"maxwidth\":\"large\",\"text_align\":\"left\",\"text_align_breakpoint\":\"s\",\"text_align_fallback\":\"center\",\"text_style\":\"lead\"}},{\"type\":\"button\",\"props\":{\"animation\":\"slide-bottom-small\",\"grid_column_gap\":\"small\",\"grid_row_gap\":\"small\",\"margin_bottom\":\"medium\",\"margin_top\":\"medium\",\"text_align\":\"left\",\"text_align_breakpoint\":\"s\",\"text_align_fallback\":\"center\"},\"children\":[{\"type\":\"button_item\",\"props\":{\"button_style\":\"primary\",\"content\":\"Contact Us\",\"dialog_layout\":\"modal\",\"dialog_offcanvas_flip\":true,\"icon_align\":\"left\",\"link\":\"mailto:info@example.com\"}}]}]}]}],\"name\":\"Call to Action\"}],\"version\":\"5.0.28\"} --><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Isla Kong Piscina Ver m\u00e1s Piscina 2 Piscina Ver m\u00e1s Piscina 1 Piscina Ver m\u00e1s Piscina de Chorros Piscina Ver m\u00e1s Piscina 3 Piscina Coming soon! Ver m\u00e1s Tobog\u00e1n Racer Tobog\u00e1n Coming soon! Ver m\u00e1s Bosque Perdido de los Dinosaurios Atracci\u00f3n Ver m\u00e1s Find Your Home Away From Home Lorem ipsum dolor sit amet, consectetur [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-92","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.festiq.one\/index.php\/wp-json\/wp\/v2\/pages\/92","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.festiq.one\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.festiq.one\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.festiq.one\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.festiq.one\/index.php\/wp-json\/wp\/v2\/comments?post=92"}],"version-history":[{"count":10,"href":"https:\/\/www.festiq.one\/index.php\/wp-json\/wp\/v2\/pages\/92\/revisions"}],"predecessor-version":[{"id":196,"href":"https:\/\/www.festiq.one\/index.php\/wp-json\/wp\/v2\/pages\/92\/revisions\/196"}],"wp:attachment":[{"href":"https:\/\/www.festiq.one\/index.php\/wp-json\/wp\/v2\/media?parent=92"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}